{"id":9125,"date":"2020-11-30T19:25:34","date_gmt":"2020-11-30T18:25:34","guid":{"rendered":"https:\/\/vinyltom.com\/produkt\/ross-diana-why-do-fools-fall-in-love\/"},"modified":"2025-02-12T13:33:03","modified_gmt":"2025-02-12T12:33:03","slug":"ross-diana-why-do-fools-fall-in-love","status":"publish","type":"product","link":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/","title":{"rendered":"ROSS DIANA why do fools fall in love"},"content":{"rendered":"<p>Title: ROSS DIANA why do fools fall in love Grading: capitol 1a064-86441\/81\/EC\/NM-\/FOC-OIS Info: eec press. 1981, orig. inner Cover: gatefold cover is near mint minus with only minimal wear, inner nm Vinyl: near mint minus with slight hairlines, labels nm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Title: ROSS DIANA why do fools fall in love Grading: capitol 1a064-86441\/81\/EC\/NM-\/FOC-OIS Info: eec press. 1981, orig. inner Cover: gatefold cover is near mint minus with only minimal wear, inner nm Vinyl: near mint minus with slight hairlines, labels nm<\/p>\n","protected":false},"featured_media":5315,"template":"","meta":[],"product_brand":[],"product_cat":[65],"product_tag":[],"class_list":{"0":"post-9125","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-soul-funk-disco","8":"first","9":"instock","10":"sale","11":"sold-individually","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ROSS DIANA why do fools fall in love - Vinyltom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROSS DIANA why do fools fall in love - Vinyltom\" \/>\n<meta property=\"og:description\" content=\"Title: ROSS DIANA why do fools fall in love Grading: capitol 1a064-86441\/81\/EC\/NM-\/FOC-OIS Info: eec press. 1981, orig. inner Cover: gatefold cover is near mint minus with only minimal wear, inner nm Vinyl: near mint minus with slight hairlines, labels nm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinyltom\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-12T12:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vinyltom.com\/wp-content\/uploads\/2020\/11\/rossd_why.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/\",\"url\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/\",\"name\":\"ROSS DIANA why do fools fall in love - Vinyltom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/vinyltom.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rossd_why.jpg?fit=300%2C300&ssl=1\",\"datePublished\":\"2020-11-30T18:25:34+00:00\",\"dateModified\":\"2025-02-12T12:33:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/vinyltom.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rossd_why.jpg?fit=300%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/vinyltom.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rossd_why.jpg?fit=300%2C300&ssl=1\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/produkt\\\/ross-diana-why-do-fools-fall-in-love\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ROSS DIANA why do fools fall in love\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/\",\"name\":\"Vinyltom the Record King and Music Specialist\",\"description\":\"Vintage Vinyl Records for Collectors\",\"publisher\":{\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/#organization\",\"name\":\"Vinyltom the Record King and Music Specialist\",\"url\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/vinyltom.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-Vinyltom_logo_druck.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/vinyltom.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-Vinyltom_logo_druck.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Vinyltom the Record King and Music Specialist\"},\"image\":{\"@id\":\"https:\\\/\\\/vinyltom.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/at.linkedin.com\\\/in\\\/vinyltom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ROSS DIANA why do fools fall in love - Vinyltom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/","og_locale":"en_US","og_type":"article","og_title":"ROSS DIANA why do fools fall in love - Vinyltom","og_description":"Title: ROSS DIANA why do fools fall in love Grading: capitol 1a064-86441\/81\/EC\/NM-\/FOC-OIS Info: eec press. 1981, orig. inner Cover: gatefold cover is near mint minus with only minimal wear, inner nm Vinyl: near mint minus with slight hairlines, labels nm","og_url":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/","og_site_name":"Vinyltom","article_modified_time":"2025-02-12T12:33:03+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/vinyltom.com\/wp-content\/uploads\/2020\/11\/rossd_why.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/","url":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/","name":"ROSS DIANA why do fools fall in love - Vinyltom","isPartOf":{"@id":"https:\/\/vinyltom.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/#primaryimage"},"image":{"@id":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/vinyltom.com\/wp-content\/uploads\/2020\/11\/rossd_why.jpg?fit=300%2C300&ssl=1","datePublished":"2020-11-30T18:25:34+00:00","dateModified":"2025-02-12T12:33:03+00:00","breadcrumb":{"@id":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/#primaryimage","url":"https:\/\/i0.wp.com\/vinyltom.com\/wp-content\/uploads\/2020\/11\/rossd_why.jpg?fit=300%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/vinyltom.com\/wp-content\/uploads\/2020\/11\/rossd_why.jpg?fit=300%2C300&ssl=1","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/vinyltom.com\/en\/produkt\/ross-diana-why-do-fools-fall-in-love\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/vinyltom.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vinyltom.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"ROSS DIANA why do fools fall in love"}]},{"@type":"WebSite","@id":"https:\/\/vinyltom.com\/en\/#website","url":"https:\/\/vinyltom.com\/en\/","name":"Vinyltom the Record King and Music Specialist","description":"Vintage Vinyl Records for Collectors","publisher":{"@id":"https:\/\/vinyltom.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vinyltom.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vinyltom.com\/en\/#organization","name":"Vinyltom the Record King and Music Specialist","url":"https:\/\/vinyltom.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vinyltom.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/vinyltom.com\/wp-content\/uploads\/2020\/11\/cropped-Vinyltom_logo_druck.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i1.wp.com\/vinyltom.com\/wp-content\/uploads\/2020\/11\/cropped-Vinyltom_logo_druck.jpg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Vinyltom the Record King and Music Specialist"},"image":{"@id":"https:\/\/vinyltom.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/at.linkedin.com\/in\/vinyltom"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/product\/9125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/media\/5315"}],"wp:attachment":[{"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/media?parent=9125"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/product_brand?post=9125"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/product_cat?post=9125"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vinyltom.com\/en\/wp-json\/wp\/v2\/product_tag?post=9125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}